{"id":996,"date":"2025-05-07T10:50:48","date_gmt":"2025-05-07T10:50:48","guid":{"rendered":"https:\/\/demo.touchtechdesign.com\/fibo\/?page_id=996"},"modified":"2025-06-09T07:47:20","modified_gmt":"2025-06-09T07:47:20","slug":"journals","status":"publish","type":"page","link":"https:\/\/demo.touchtechdesign.com\/fibo\/research\/journals\/","title":{"rendered":"\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23"},"content":{"rendered":"\n<div class=\"gb-element-fde9cc7b alignfull\">\n<h2 class=\"gb-text-ed9a6244\"><span class=\"gb-shape\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"200\" height=\"50\">   <line style=\"stroke:#dd5900;stroke-width:4\" y2=\"30\" x2=\"300\" y1=\"30\" x1=\"0\"><\/line> <\/svg><\/span><span class=\"gb-text\"><strong>\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23<\/strong><\/span><\/h2>\n<\/div>\n\n\n\n<div class=\"gb-element-f5b83de6 alignfull\">\n<div class=\"gb-element-e52702e0\"><style>.kt-accordion-id996_7de2f0-0e .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:10px;}.kt-accordion-id996_7de2f0-0e .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;background:#ffffff;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id996_7de2f0-0e .wp-block-kadence-pane .kt-accordion-header-wrap .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;border-top-left-radius:6px;border-top-right-radius:6px;border-bottom-right-radius:6px;border-bottom-left-radius:6px;background:#16317a;color:#f5f5f7;padding-top:14px;padding-right:16px;padding-bottom:14px;padding-left:16px;}.kt-accordion-id996_7de2f0-0e:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id996_7de2f0-0e:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-icon-trigger:before{background:#f5f5f7;}.kt-accordion-id996_7de2f0-0e:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#f5f5f7;}.kt-accordion-id996_7de2f0-0e:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id996_7de2f0-0e:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#16317a;}.kt-accordion-id996_7de2f0-0e .kt-accordion-header-wrap .kt-blocks-accordion-header:hover, body:not(.hide-focus-outline) .kt-accordion-id996_7de2f0-0e .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible{color:#f5f5f7;background:#dd5900;border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id996_7de2f0-0e:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id996_7de2f0-0e:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id996_7de2f0-0e:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id996_7de2f0-0e:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#f5f5f7;}.kt-accordion-id996_7de2f0-0e:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id996_7de2f0-0e:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#f5f5f7;}.kt-accordion-id996_7de2f0-0e:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id996_7de2f0-0e:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id996_7de2f0-0e:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id996_7de2f0-0e:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#dd5900;}.kt-accordion-id996_7de2f0-0e .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible, .kt-accordion-id996_7de2f0-0e .kt-accordion-header-wrap .kt-blocks-accordion-header.kt-accordion-panel-active{color:#f5f5f7;background:#16317a;border-top-color:#BE530B;border-top-style:solid;border-right-color:#BE530B;border-right-style:solid;border-bottom-color:#BE530B;border-bottom-style:solid;border-left-color:#BE530B;border-left-style:solid;}.kt-accordion-id996_7de2f0-0e:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id996_7de2f0-0e:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#f5f5f7;}.kt-accordion-id996_7de2f0-0e:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#f5f5f7;}.kt-accordion-id996_7de2f0-0e:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id996_7de2f0-0e:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#16317a;}@media all and (max-width: 1024px){.kt-accordion-id996_7de2f0-0e .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id996_7de2f0-0e .wp-block-kadence-pane .kt-accordion-header-wrap .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}}@media all and (max-width: 1024px){.kt-accordion-id996_7de2f0-0e .kt-accordion-header-wrap .kt-blocks-accordion-header:hover, body:not(.hide-focus-outline) .kt-accordion-id996_7de2f0-0e .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id996_7de2f0-0e .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible, .kt-accordion-id996_7de2f0-0e .kt-accordion-header-wrap .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#BE530B;border-top-style:solid;border-right-color:#BE530B;border-right-style:solid;border-bottom-color:#BE530B;border-bottom-style:solid;border-left-color:#BE530B;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id996_7de2f0-0e .kt-accordion-inner-wrap{display:block;}.kt-accordion-id996_7de2f0-0e .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:10px;}.kt-accordion-id996_7de2f0-0e .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id996_7de2f0-0e .wp-block-kadence-pane .kt-accordion-header-wrap .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}.kt-accordion-id996_7de2f0-0e .kt-accordion-header-wrap .kt-blocks-accordion-header:hover, body:not(.hide-focus-outline) .kt-accordion-id996_7de2f0-0e .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id996_7de2f0-0e .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible, .kt-accordion-id996_7de2f0-0e .kt-accordion-header-wrap .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#BE530B;border-top-style:solid;border-right-color:#BE530B;border-right-style:solid;border-bottom-color:#BE530B;border-bottom-style:solid;border-left-color:#BE530B;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id996_7de2f0-0e kt-accordion-has-6-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-basic kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"0\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-6 kt-pane996_67c8be-1b\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e1b\u0e37 2556<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"gb-text gb-text-99078bce\"><a href=\"https:\/\/demo.touchtechdesign.com\/fibo\/wp-content\/uploads\/2025\/06\/\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23-2556.pdf\">Download<\/a><\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-6 kt-pane996_67c8be-1b\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e1b\u0e37 2557<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"gb-text gb-text-99078bce\"><a href=\"https:\/\/demo.touchtechdesign.com\/fibo\/wp-content\/uploads\/2025\/06\/\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23-2557.pdf\" data-type=\"link\" data-id=\"https:\/\/demo.touchtechdesign.com\/fibo\/wp-content\/uploads\/2025\/06\/\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23-2557.pdf\">Download<\/a><\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-6 kt-pane996_67c8be-1b\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e1b\u0e37 2558<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"gb-text gb-text-99078bce\"><a href=\"https:\/\/demo.touchtechdesign.com\/fibo\/wp-content\/uploads\/2025\/06\/\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23-2558.pdf\" data-type=\"link\" data-id=\"https:\/\/demo.touchtechdesign.com\/fibo\/wp-content\/uploads\/2025\/06\/\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23-2558.pdf\">Download<\/a><\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-5 kt-pane996_03f635-46\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e1b\u0e37 2559<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"gb-text gb-text-99078bce\"><a href=\"https:\/\/demo.touchtechdesign.com\/fibo\/wp-content\/uploads\/2025\/06\/\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23-2559.pdf\" data-type=\"link\" data-id=\"https:\/\/demo.touchtechdesign.com\/fibo\/wp-content\/uploads\/2025\/06\/\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23-2559.pdf\">Download<\/a><\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-5 kt-pane996_0e4d3d-02\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e1b\u0e37 2560<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"gb-text gb-text-99078bce\"><a href=\"https:\/\/demo.touchtechdesign.com\/fibo\/wp-content\/uploads\/2025\/06\/\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23-2560.pdf\">Download<\/a><\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-5 kt-pane996_67c8be-1b\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e1b\u0e37 2561<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"gb-text gb-text-99078bce\"><a href=\"https:\/\/demo.touchtechdesign.com\/fibo\/wp-content\/uploads\/2025\/06\/\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23-2561.pdf\" data-type=\"link\" data-id=\"https:\/\/demo.touchtechdesign.com\/fibo\/wp-content\/uploads\/2025\/06\/\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23-2561.pdf\">Download<\/a><\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-4 kt-pane996_1a19c2-61\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e1b\u0e37 2562<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"gb-text gb-text-99078bce\"><a href=\"https:\/\/demo.touchtechdesign.com\/fibo\/wp-content\/uploads\/2025\/06\/\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23-2562.pdf\" data-type=\"link\" data-id=\"https:\/\/demo.touchtechdesign.com\/fibo\/wp-content\/uploads\/2025\/06\/\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23-2562.pdf\">Download<\/a><\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-4 kt-pane996_368bad-fe\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e1b\u0e37 2563<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"gb-text gb-text-99078bce\"><a href=\"https:\/\/demo.touchtechdesign.com\/fibo\/wp-content\/uploads\/2025\/06\/\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23-2563.pdf\">Download<\/a><\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-4 kt-pane996_dd76a3-d9\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e1b\u0e37 2564<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"gb-text gb-text-99078bce\"><a href=\"https:\/\/demo.touchtechdesign.com\/fibo\/wp-content\/uploads\/2025\/06\/\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23-2564.pdf\" data-type=\"link\" data-id=\"https:\/\/demo.touchtechdesign.com\/fibo\/wp-content\/uploads\/2025\/06\/\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23-2564.pdf\">Download<\/a><\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane996_22a1d5-d4\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e1b\u0e37 2565<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"gb-text gb-text-99078bce\"><a href=\"https:\/\/demo.touchtechdesign.com\/fibo\/wp-content\/uploads\/2025\/06\/\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23-2565.pdf\">Download<\/a><\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane996_240d5d-55\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e1b\u0e37 2566<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"gb-text gb-text-ce368fba\"><a href=\"https:\/\/demo.touchtechdesign.com\/fibo\/wp-content\/uploads\/2025\/06\/\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23-2566.pdf\" data-type=\"link\" data-id=\"https:\/\/demo.touchtechdesign.com\/fibo\/wp-content\/uploads\/2025\/06\/\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23-2566.pdf\">Download<\/a><\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":3134,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-996","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/demo.touchtechdesign.com\/fibo\/wp-json\/wp\/v2\/pages\/996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.touchtechdesign.com\/fibo\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demo.touchtechdesign.com\/fibo\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demo.touchtechdesign.com\/fibo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/demo.touchtechdesign.com\/fibo\/wp-json\/wp\/v2\/comments?post=996"}],"version-history":[{"count":9,"href":"https:\/\/demo.touchtechdesign.com\/fibo\/wp-json\/wp\/v2\/pages\/996\/revisions"}],"predecessor-version":[{"id":4566,"href":"https:\/\/demo.touchtechdesign.com\/fibo\/wp-json\/wp\/v2\/pages\/996\/revisions\/4566"}],"up":[{"embeddable":true,"href":"https:\/\/demo.touchtechdesign.com\/fibo\/wp-json\/wp\/v2\/pages\/3134"}],"wp:attachment":[{"href":"https:\/\/demo.touchtechdesign.com\/fibo\/wp-json\/wp\/v2\/media?parent=996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}